{"id":28497,"date":"2026-05-13T09:11:15","date_gmt":"2026-05-13T07:11:15","guid":{"rendered":"https:\/\/www.enerlandgroup.com\/?p=28497"},"modified":"2026-05-13T09:17:05","modified_gmt":"2026-05-13T07:17:05","slug":"xii-carrera-solidaria-atades","status":"publish","type":"post","link":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/","title":{"rendered":"XII Carrera Solidaria Atades"},"content":{"rendered":"<h2>Varios trabajadores de Enerland Group en Zaragoza (Espa\u00f1a), participaron el pasado 10 de mayo en la XII Carrera Solidaria Atades. Los beneficios de esta competici\u00f3n van destinados al programa de Atades para terapia a ni\u00f1os y j\u00f3venes con necesidades especiales.<\/h2>\n<p>&nbsp;<\/p>\n<p>Por quinto a\u00f1o consecutivo, Enerland Group ha formado parte de la marea de corredores en la <a href=\"https:\/\/www.atades.org\/eventos\/xii-carrera-solidaria-atades\/\">Carrera Solidaria Atades<\/a>, que este 2026 celebraba su duod\u00e9cima edici\u00f3n. El evento tiene lugar cada mayo en el Parque Grande Jos\u00e9 Antonio Labordeta, en Zaragoza (Espa\u00f1a). Como viene siendo habitual, toda la recaudaci\u00f3n de esta carrera va destinada a las causas ben\u00e9ficas de la asociaci\u00f3n. En esta ocasi\u00f3n, su objetivo era el de ampliar el programa de becas para las terapias de ni\u00f1os con necesidades especiales.<\/p>\n<p>Entre los m\u00e1s de 3.500 participantes, fueron varios los trabajadores de Enerland que vistieron la camiseta azul y naranja para correr las distintas modalidades de la competici\u00f3n, de 1K y 5K. Para aquellos compa\u00f1eros interesados, tambi\u00e9n se facilit\u00f3 la posibilidad de inscripci\u00f3n en la modalidad \u00abDorsal Cero\u00bb, una participaci\u00f3n simb\u00f3lica en forma de donativo. Una iniciativa que celebra la solidaridad y el deporte, y que cada primavera permite a Atades facilitar recursos a quienes m\u00e1s lo necesitan.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28515 size-large\" src=\"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/f7601560-5628-48e0-a1ed-7317c5d5b9e2-2-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/f7601560-5628-48e0-a1ed-7317c5d5b9e2-2-980x735.jpg 980w, https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/f7601560-5628-48e0-a1ed-7317c5d5b9e2-2-480x360.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Enerland Group, comprometido con el deporte<\/h3>\n<p>&nbsp;<\/p>\n<p>La carrera Atades es solo una de las citas recurrentes de la compa\u00f1\u00eda en relaci\u00f3n a la actividad f\u00edsica. De forma anual, Enerland Espa\u00f1a celebra su tradicional\u00a0<a href=\"https:\/\/www.enerlandgroup.com\/es\/iv-torneo-de-padel-enerland\/\">Torneo de P\u00e1del<\/a>, as\u00ed como un partido de f\u00fatbol entre trabajadores en oto\u00f1o. Adem\u00e1s, la compa\u00f1\u00eda promueve y subvenciona diversos eventos deportivos para los trabajadores de la sede central en Zaragoza (Espa\u00f1a). Entre ellos, la Liga MLA o la Carrera de Empresas ESIC, que se celebra cada diciembre en la capital aragonesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varios trabajadores de Enerland Group en Zaragoza (Espa\u00f1a), participaron el pasado 10 de mayo<\/p>\n","protected":false},"author":19,"featured_media":28512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,161],"tags":[],"class_list":["post-28497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable<\/title>\n<meta name=\"description\" content=\"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable\" \/>\n<meta property=\"og:description\" content=\"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/\" \/>\n<meta property=\"og:site_name\" content=\"Enerland Energ\u00eda Renovable\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T07:11:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1870\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rocio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/\"},\"author\":{\"name\":\"Rocio\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#\\\/schema\\\/person\\\/1f18cbd1e1ccaf6e4ae23f4d83ccb0b3\"},\"headline\":\"XII Carrera Solidaria Atades\",\"datePublished\":\"2026-05-13T07:11:15+00:00\",\"dateModified\":\"2026-05-13T07:17:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/XII-Carrera-Atades.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/\",\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/\",\"name\":\"XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/XII-Carrera-Atades.jpg\",\"datePublished\":\"2026-05-13T07:11:15+00:00\",\"dateModified\":\"2026-05-13T07:17:05+00:00\",\"description\":\"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/XII-Carrera-Atades.jpg\",\"contentUrl\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/XII-Carrera-Atades.jpg\",\"width\":1870,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/xii-carrera-solidaria-atades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XII Carrera Solidaria Atades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/\",\"name\":\"Enerland Energ\u00eda Renovable\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#organization\",\"name\":\"Enerland Group\",\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo_Enerland.png\",\"contentUrl\":\"https:\\\/\\\/www.enerlandgroup.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo_Enerland.png\",\"width\":184,\"height\":43,\"caption\":\"Enerland Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enerland-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCjdInbThgaPa2_D34vRChmA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/#\\\/schema\\\/person\\\/1f18cbd1e1ccaf6e4ae23f4d83ccb0b3\",\"name\":\"Rocio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g\",\"caption\":\"Rocio\"},\"url\":\"https:\\\/\\\/www.enerlandgroup.com\\\/es\\\/author\\\/rocio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable","description":"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/","og_locale":"es_ES","og_type":"article","og_title":"XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable","og_description":"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.","og_url":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/","og_site_name":"Enerland Energ\u00eda Renovable","article_published_time":"2026-05-13T07:11:15+00:00","article_modified_time":"2026-05-13T07:17:05+00:00","og_image":[{"width":1870,"height":700,"url":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","type":"image\/jpeg"}],"author":"Rocio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#article","isPartOf":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/"},"author":{"name":"Rocio","@id":"https:\/\/www.enerlandgroup.com\/es\/#\/schema\/person\/1f18cbd1e1ccaf6e4ae23f4d83ccb0b3"},"headline":"XII Carrera Solidaria Atades","datePublished":"2026-05-13T07:11:15+00:00","dateModified":"2026-05-13T07:17:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/www.enerlandgroup.com\/es\/#organization"},"image":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","articleSection":["Actualidad","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/","url":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/","name":"XII Carrera Solidaria Atades - Enerland Energ\u00eda Renovable","isPartOf":{"@id":"https:\/\/www.enerlandgroup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#primaryimage"},"image":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","datePublished":"2026-05-13T07:11:15+00:00","dateModified":"2026-05-13T07:17:05+00:00","description":"Enerland Group participa un a\u00f1o m\u00e1s en la Carrera Solidaria Atades, que celebr\u00f3 su XII edici\u00f3n el pasado mayo en Zaragoza.","breadcrumb":{"@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#primaryimage","url":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","contentUrl":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","width":1870,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.enerlandgroup.com\/es\/xii-carrera-solidaria-atades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.enerlandgroup.com\/es\/"},{"@type":"ListItem","position":2,"name":"XII Carrera Solidaria Atades"}]},{"@type":"WebSite","@id":"https:\/\/www.enerlandgroup.com\/es\/#website","url":"https:\/\/www.enerlandgroup.com\/es\/","name":"Enerland Energ\u00eda Renovable","description":"","publisher":{"@id":"https:\/\/www.enerlandgroup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enerlandgroup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.enerlandgroup.com\/es\/#organization","name":"Enerland Group","url":"https:\/\/www.enerlandgroup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.enerlandgroup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2021\/05\/Logo_Enerland.png","contentUrl":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2021\/05\/Logo_Enerland.png","width":184,"height":43,"caption":"Enerland Group"},"image":{"@id":"https:\/\/www.enerlandgroup.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/enerland-group\/","https:\/\/www.youtube.com\/channel\/UCjdInbThgaPa2_D34vRChmA"]},{"@type":"Person","@id":"https:\/\/www.enerlandgroup.com\/es\/#\/schema\/person\/1f18cbd1e1ccaf6e4ae23f4d83ccb0b3","name":"Rocio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c464dd644b9d33ee1a01d4b08672fe8285d801accf8ebca0aa60d46dbebfb9b7?s=96&d=mm&r=g","caption":"Rocio"},"url":"https:\/\/www.enerlandgroup.com\/es\/author\/rocio\/"}]}},"jetpack_featured_media_url":"https:\/\/www.enerlandgroup.com\/wp-content\/uploads\/2026\/05\/XII-Carrera-Atades.jpg","_links":{"self":[{"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/posts\/28497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/comments?post=28497"}],"version-history":[{"count":8,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/posts\/28497\/revisions"}],"predecessor-version":[{"id":28524,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/posts\/28497\/revisions\/28524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/media\/28512"}],"wp:attachment":[{"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/media?parent=28497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/categories?post=28497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enerlandgroup.com\/es\/wp-json\/wp\/v2\/tags?post=28497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}